{"id":65,"count":27,"description":"","link":"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/","name":"Hotel Bedding","slug":"hotel-bedding","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hotel Bedding Archives - kkrlinens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel Bedding Archives - kkrlinens\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/\" \/>\n<meta property=\"og:site_name\" content=\"kkrlinens\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/category\\\/hotel-bedding\\\/\",\"url\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/category\\\/hotel-bedding\\\/\",\"name\":\"Hotel Bedding Archives - kkrlinens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/category\\\/hotel-bedding\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/category\\\/hotel-bedding\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel Bedding\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/\",\"name\":\"kkrlinens\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/#organization\",\"name\":\"kkrlinens\",\"url\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-logo.png\",\"contentUrl\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-logo.png\",\"width\":631,\"height\":200,\"caption\":\"kkrlinens\"},\"image\":{\"@id\":\"https:\\\/\\\/kkrlinens.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel Bedding Archives - kkrlinens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/","og_locale":"en_US","og_type":"article","og_title":"Hotel Bedding Archives - kkrlinens","og_url":"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/","og_site_name":"kkrlinens","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/","url":"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/","name":"Hotel Bedding Archives - kkrlinens","isPartOf":{"@id":"https:\/\/kkrlinens.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/kkrlinens.com\/blog\/category\/hotel-bedding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kkrlinens.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Hotel Bedding"}]},{"@type":"WebSite","@id":"https:\/\/kkrlinens.com\/blog\/#website","url":"https:\/\/kkrlinens.com\/blog\/","name":"kkrlinens","description":"","publisher":{"@id":"https:\/\/kkrlinens.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kkrlinens.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kkrlinens.com\/blog\/#organization","name":"kkrlinens","url":"https:\/\/kkrlinens.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kkrlinens.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/kkrlinens.com\/blog\/wp-content\/uploads\/2025\/10\/cropped-logo.png","contentUrl":"https:\/\/kkrlinens.com\/blog\/wp-content\/uploads\/2025\/10\/cropped-logo.png","width":631,"height":200,"caption":"kkrlinens"},"image":{"@id":"https:\/\/kkrlinens.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kkrlinens.com\/blog\/wp-json\/wp\/v2\/categories\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kkrlinens.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kkrlinens.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kkrlinens.com\/blog\/wp-json\/wp\/v2\/posts?categories=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}